{"id":9810,"date":"2026-07-15T17:46:04","date_gmt":"2026-07-15T09:46:04","guid":{"rendered":"https:\/\/bogonglaser.com\/?post_type=product&#038;p=9810"},"modified":"2026-07-15T17:50:50","modified_gmt":"2026-07-15T09:50:50","slug":"backpack-laser-cleaning-machine-portable-pulse-laser-rust-paint-removal-equipment","status":"publish","type":"product","link":"https:\/\/bogonglaser.com\/it\/backpack-laser-cleaning-machine-portable-pulse-laser-rust-paint-removal-equipment\/","title":{"rendered":"Macchina per la pulizia laser a zaino"},"content":{"rendered":"<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h2 class=\"heading-2 ace-line old-record-id-IX5Kfn6o5dagfgc3mhKccN7In9d\">Introduzione: Che cos\u2019\u00e8 una macchina per la pulizia laser a zaino?<\/h2>\n<figure id=\"attachment_9814\" aria-describedby=\"caption-attachment-9814\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-9814\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG.jpg\" alt=\"Pulitore laser da zaino BOGONG\" width=\"800\" height=\"400\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG.jpg 800w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG-300x150.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG-768x384.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG-18x9.jpg 18w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-BOGONG-600x300.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-9814\" class=\"wp-caption-text\">Pulitore laser da zaino BOGONG<\/figcaption><\/figure>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-Wa1pfZpRHdKRUscYxibcY31Wnfg\">La macchina per la pulizia laser a zaino \u00e8 un dispositivo portatile di nuova generazione per il trattamento delle superfici industriali. Adotta una tecnologia avanzata a laser a fibra pulsata. A differenza delle tradizionali macchine per la pulizia laser su carrello, questo dispositivo \u00e8 caratterizzato da una struttura a zaino indossabile. Integra la sorgente laser, il sistema di controllo, il modulo di raffreddamento e la batteria al litio in un\u2019unica unit\u00e0 compatta.<\/div>\n<div class=\"ace-line ace-line old-record-id-NitvfifGWdvp94cf0WPcCJFtn9g\">Questo modello libera completamente gli utenti dai vincoli legati al luogo di utilizzo e all'alimentazione elettrica. Offre prestazioni di pulizia di livello industriale in un formato ultraportatile. Rimuove in modo professionale ruggine, vernice, macchie di olio, strati di ossido, scorie di saldatura e rivestimenti superficiali. \u00c8 la soluzione ideale per la manutenzione all'aperto, gli interventi in quota e le operazioni di pulizia in spazi ristretti.<\/div>\n<div class=\"ace-line ace-line old-record-id-Ur42fMuo0dWapccZCoDcM4VcnVf\">I metodi di pulizia tradizionali presentano evidenti difetti. La sabbiatura provoca un'elevata produzione di polvere e danni al substrato. La pulizia chimica comporta inquinamento e rischi nascosti per la sicurezza. La lucidatura manuale richiede molto tempo ed \u00e8 inefficiente. La macchina per la pulizia laser a zaino risolve tutti questi problemi. Consente una pulizia delle superfici non invasiva, ecologica e ad alta efficienza, senza alcun consumo di materiali di consumo.<\/div>\n<div>\n<p><iframe title=\"Pulizia con Laser a zaino: macchina per la pulizia portatile | Macchina per la pulizia laser da 100 W, 200 W e 300 W\" width=\"1290\" height=\"726\" src=\"https:\/\/www.youtube.com\/embed\/o8XO3bdZO-s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<div>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h2 class=\"heading-2 ace-line old-record-id-YvAxfh8gZd0c0QckNfIciv3NnDb\">Vantaggi principali della macchina per la pulizia laser a zaino<\/h2>\n<h3 class=\"heading-3 ace-line old-record-id-WcvFfQfHtdQbMTc8RWecFY7Onud\">Design indossabile ultraportatile, senza alcuna limitazione di utilizzo<\/h3>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-Iy46fotMVdsYYRcPfOYcjoS6n3g\">La macchina \u00e8 leggera e compatta. \u00c8 dotata di una struttura ergonomica che ne consente il trasporto a zaino. Gli operatori possono trasportarla e spostarla liberamente. Non sono necessarie attrezzature ingombranti n\u00e9 strumenti di trazione. \u00c8 ideale per l\u2019uso in officine di dimensioni ridotte, su attrezzature situate in quota, all\u2019esterno degli edifici e in cantieri remoti.<\/div>\n<div class=\"ace-line ace-line old-record-id-OCkOfwhSpdWt6Xc2TQWcq0gRnTf\">Supporta il funzionamento wireless alimentato a batteria. La batteria al litio integrata ad alta capacit\u00e0 garantisce una lunga autonomia. Pu\u00f2 funzionare normalmente in luoghi privi di alimentazione di rete. Rispetto ai pulitori laser fissi e su carrello, offre una mobilit\u00e0 e una flessibilit\u00e0 senza pari.<\/div>\n<div>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-QMGSfy8Ird0TzAcm59ecnMFlneh\">\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h3 class=\"heading-3 ace-line old-record-id-W6GZfrL3sd7XAocGimFcuCPMnLd\">Funzionamento semplice e controllo intelligente, facile da usare<\/h3>\n<\/div>\n<\/div>\n<div>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-C0dPf4E5wdCaMgcPsUEcpjJJnHb\">Dotato di uno schermo tattile intelligente portatile.<\/div>\n<div>\n<figure id=\"attachment_9815\" aria-describedby=\"caption-attachment-9815\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-9815\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1.jpg\" alt=\"macchina per la pulizia laser a zaino\" width=\"800\" height=\"400\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1.jpg 800w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1-300x150.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1-768x384.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1-18x9.jpg 18w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machine-1-600x300.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-9815\" class=\"wp-caption-text\">macchina per la pulizia laser a zaino<\/figcaption><\/figure>\n<\/div>\n<div class=\"ace-line ace-line old-record-id-C0dPf4E5wdCaMgcPsUEcpjJJnHb\">Dispone di numerosi modelli predefiniti di parametri di pulizia specifici per il settore. Gli utenti possono passare da una modalit\u00e0 all'altra con un solo clic, a seconda dei materiali e delle macchie.<\/div>\n<div class=\"ace-line ace-line old-record-id-NHuLftVWTdRHYocinI0c5MyinBc\">La testina laser portatile \u00e8 leggera e flessibile. Consente la pulizia tramite scansione multiangolare. \u00c8 in grado di coprire superfici curve complesse, angoli e pezzi di forma irregolare. Gli operatori possono imparare a utilizzarla in breve tempo senza bisogno di competenze tecniche specifiche.<\/div>\n<div>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h3 class=\"old-record-id-QAvEfEwZede5e7cEalDcktign7e\">Ampia gamma di scenari applicativi<\/h3>\n<figure id=\"attachment_9820\" aria-describedby=\"caption-attachment-9820\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-9820\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine.jpg\" alt=\"pulizia laser dello zaino per macchina per la pulizia delle pareti\" width=\"800\" height=\"600\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine.jpg 800w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine-300x225.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine-768x576.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine-16x12.jpg 16w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-for-wall-cleaning-machine-600x450.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-9820\" class=\"wp-caption-text\">pulizia laser dello zaino per macchina per la pulizia delle pareti<\/figcaption><\/figure>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h3 class=\"heading-3 ace-line old-record-id-GwHZf9TppdGhG7cJWJnclf6Gnpg\">Manutenzione delle attrezzature industriali<\/h3>\n<div class=\"ace-line ace-line old-record-id-CHWgfiu8JdoagUcAGTVczKixnme\">Elimina la ruggine e l'olio da attrezzature meccaniche, stampi e supporti metallici. Rimuove gli strati di ossido superficiali e le scorie di saldatura. Ripristina le prestazioni delle superfici delle attrezzature. \u00c8 ampiamente utilizzato nelle fabbriche di macchinari, nelle case automobilistiche e nelle officine di lavorazione.<\/div>\n<h3 class=\"heading-3 ace-line old-record-id-UpWufvTDMdKqh1crl5QcjaHmnQg\">Pulizia tecnica in ambienti esterni e ad alta quota<\/h3>\n<div class=\"ace-line ace-line old-record-id-HWYNfkKwTdcU9ucA4GvchOuLnMc\">\u00c8 indicato per la rimozione della ruggine e della vernice da strutture in acciaio, ponti, parapetti e gru a torre. Il suo design portatile e indossabile lo rende adatto a interventi in quota e in ambienti esterni dove non \u00e8 possibile spostare le attrezzature. Risolve il problema della pulizia delle grandi attrezzature fisse.<\/div>\n<h3 class=\"heading-3 ace-line old-record-id-D7fufgyD5dtrSNchss8c5oMkntg\">Restauro di beni culturali e del legno<\/h3>\n<div class=\"ace-line ace-line old-record-id-PFcvfpr2RdvgFncnRVecOrF0n3d\">Grazie alla sua capacit\u00e0 di pulizia precisa e a basso impatto, rimuove lo sporco superficiale, la vernice vecchia e la ruggine da oggetti d\u2019antiquariato in legno, reperti culturali in metallo e sculture in pietra. Preserva la texture originale dei reperti culturali. \u00c8 uno strumento professionale destinato agli istituti di restauro dei beni culturali.<\/div>\n<h3 class=\"heading-3 ace-line old-record-id-BTbWf5cFOdX9IocGbtwcOUO7nZb\">Settore automobilistico e aerospaziale<\/h3>\n<div class=\"ace-line ace-line old-record-id-U9NnfHYiqdZskbcS8r7cGCGKnPb\">Rimuove l'olio dalla superficie del motore, la ruggine dai mozzi delle ruote e i vecchi rivestimenti dalla carrozzeria. Esegue la pulizia di pretrattamento e di ripristino per componenti di precisione del settore aerospaziale. Garantisce l'assenza di danni ai pezzi di alta precisione e migliora il tasso di qualificazione dei prodotti.<\/div>\n<h3 class=\"heading-3 ace-line old-record-id-GOntfmxiGddilCcwIhNc0NAcnXh\">Ingegneria navale e marittima<\/h3>\n<div class=\"ace-line ace-line old-record-id-PcEhfYseWdGt6OcCXDRczZNknlc\">Rimuove la ruggine marina, la corrosione da nebbia salina e i vecchi rivestimenti anticorrosivi dalle superfici delle navi e dalle attrezzature offshore. Risolve efficacemente i problemi di corrosione dei metalli in ambiente marino e prolunga la durata delle attrezzature.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<h4>Dimensioni del pulitore laser a zaino da 300 W:<\/h4>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9816\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-scaled.jpg\" alt=\"\" width=\"730\" height=\"454\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-scaled.jpg 2560w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-300x187.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-1024x637.jpg 1024w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-768x478.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-1536x956.jpg 1536w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-2048x1274.jpg 2048w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-18x12.jpg 18w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-size-600x373.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/p>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h2 class=\"heading-2 ace-line old-record-id-GIGcfzf2dd5ueucjeVXcEwmSnNb\">Caratteristiche tecniche del prodotto e garanzia di sicurezza<\/h2>\n<div class=\"ace-line ace-line old-record-id-SrlzfGiAPdyQQPcOrTlcV4cWnKf\">La macchina per la pulizia laser a zaino supporta diverse modalit\u00e0 di scansione, tra cui quella circolare, a croce e a forma di S. Consente di personalizzare la velocit\u00e0 di pulizia e la potenza del laser. Si adatta alle diverse esigenze di pulizia in base ai vari materiali e allo spessore delle macchie.<\/div>\n<div class=\"ace-line ace-line old-record-id-W8M2ftaRjdQKY6cBY3Gc0fctnpg\">\u00c8 dotata di sistemi di protezione di sicurezza all'avanguardia. Dispone di un interruttore di arresto di emergenza, di un blocco di sicurezza del laser e di un sistema di assistenza alla messa a fuoco con luce rossa. Previene le fughe di laser e i rischi operativi. L'intera macchina \u00e8 certificata CE e RoHS. \u00c8 conforme agli standard internazionali di sicurezza industriale.<\/div>\n<div class=\"ace-line ace-line old-record-id-KhmlfmjWod8JCLcrk7pc9hernfa\">La funzione di memoria intelligente salva le impostazioni dei parametri utilizzati pi\u00f9 di frequente. Ci\u00f2 evita di dover ripetere il debug e migliora l'efficienza lavorativa. Il cavo in fibra ottica a lunga distanza consente un funzionamento flessibile in aree di lavoro di ampia estensione.<\/div>\n<div>\n<div data-page-id=\"R1Radl9wao0jUXxA5sAcS6PPnvb\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\">\n<h2 class=\"heading-2 ace-line old-record-id-SxHlf7ot0dQe6TcrroScDP0sn4c\">Invito all'acquisto e alla collaborazione<\/h2>\n<div class=\"ace-line ace-line old-record-id-TdvvfHfsZd8Q0KcLlKgcXta1npf\">Se siete alla ricerca di attrezzature per la pulizia industriale efficienti, ecologiche e portatili, la nostra macchina per la pulizia laser a zaino \u00e8 la scelta migliore. \u00c8 ampiamente apprezzata dai clienti nei settori della produzione di macchinari, della manutenzione ingegneristica, del restauro di beni culturali e dell'industria navale.<\/div>\n<div>\n<figure id=\"attachment_9817\" aria-describedby=\"caption-attachment-9817\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-9817\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines.jpg\" alt=\"macchine per la pulizia laser a zaino\" width=\"800\" height=\"400\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines.jpg 800w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines-300x150.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines-768x384.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines-18x9.jpg 18w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaning-machines-600x300.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-9817\" class=\"wp-caption-text\">macchine per la pulizia laser a zaino<\/figcaption><\/figure>\n<p>Confezione della macchina per la pulizia laser a zaino<\/p>\n<figure id=\"attachment_9818\" aria-describedby=\"caption-attachment-9818\" style=\"width: 803px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-9818\" src=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price.jpg\" alt=\"prezzo del pulitore laser a zaino\" width=\"803\" height=\"321\" title=\"\" srcset=\"https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price.jpg 1000w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price-300x120.jpg 300w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price-768x307.jpg 768w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price-18x7.jpg 18w, https:\/\/bogonglaser.com\/wp-content\/uploads\/2026\/07\/backpack-laser-cleaner-price-600x240.jpg 600w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><figcaption id=\"caption-attachment-9818\" class=\"wp-caption-text\">pulitore laser a zaino:<\/figcaption><\/figure>\n<pre><strong>Macchina laser a zaino da 300 W<\/strong>\r\n<strong>Peso netto: 13,47 kg<\/strong>\r\n<strong>Dimensioni dell'imballaggio: 88*86*39 cm <\/strong>\r\n<strong>Peso lordo: 55,7 kg<\/strong><\/pre>\n<\/div>\n<div class=\"ace-line ace-line old-record-id-Du14fucAndzzgycGVTkcpB9rncd\">Non esitate a contattarci per una consulenza gratuita sui parametri, un test di pulizia su campione e un preventivo a prezzo di fabbrica. Forniamo soluzioni affidabili di pulizia laser a clienti industriali in tutto il mondo e creiamo un maggiore valore economico per la vostra attivit\u00e0.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La nostra macchina per la pulizia laser a zaino \u00e8 un dispositivo leggero e completamente portatile che utilizza la tecnologia laser a impulsi. \u00c8 caratterizzata da un design indossabile e da una batteria integrata, che consentono un funzionamento senza cavi per la pulizia all\u2019aperto, in quota e in spazi ristretti. Rimuove in modo sicuro ruggine, vernice, olio, strati di ossido e scorie di saldatura senza danneggiare il materiale di base. Ecologica e senza materiali di consumo, sostituisce la tradizionale sabbiatura e la pulizia chimica. Ideale per la manutenzione industriale, il settore aerospaziale, la riparazione navale e il restauro di beni culturali.<\/p>","protected":false},"featured_media":9811,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[94],"product_tag":[890,887,888,889,886],"class_list":["post-9810","product","type-product","status-publish","has-post-thumbnail","product_cat-laser-cleaning-machine","product_tag-backpack-cleaner","product_tag-backpack-laser-cleaning-machine","product_tag-backpack-laser-cleaning-system","product_tag-backpack-laser-system","product_tag-packpack-laser-cleaner","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/product\/9810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/media\/9811"}],"wp:attachment":[{"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/media?parent=9810"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/product_brand?post=9810"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/product_cat?post=9810"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bogonglaser.com\/it\/wp-json\/wp\/v2\/product_tag?post=9810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}